{"id":7,"date":"2021-10-06T18:17:14","date_gmt":"2021-10-06T18:17:14","guid":{"rendered":"https:\/\/www.campingehrwald.at\/?page_id=7"},"modified":"2021-10-22T12:17:43","modified_gmt":"2021-10-22T10:17:43","slug":"datenschutzvereinbarungen","status":"publish","type":"page","link":"https:\/\/campingehrwald.at\/nl\/datenschutzvereinbarungen\/","title":{"rendered":"Gegevensbeschermingsovereenkomsten"},"content":{"rendered":"<h1>Privacy Policy<\/h1><p><p>In dieser Datenschutzerkl\u00e4rung informieren wir Sie \u00fcber die Verarbeitung Ihrer personenbezogenen Daten.<\/p><p> Sofern Sie Ihre Datenschutzeinstellungen \u00e4ndern m\u00f6chten (Einwilligungen erteilen oder bereits erteilte Einwilligungen widerrufen), klicken Sie <a target=\"_blank\" href=\"#\" class=\"sp-dsgvo-show-privacy-popup\">hier<\/a> um Ihre Einstellungen zu \u00e4ndern.<\/p><h2>Responsible<\/h2><p>Anja Schmid, Camping Dr. Lauth, Zugspitzstra\u00dfe 34, 6632 Ehrwald, \u00d6sterreich, <a href=\"mailto:info@campingehrwald.at\">info@campingehrwald.at<\/a>, +43 5673 2666<\/p><h2>Hosting<\/h2><p><strong>Anbieter: <\/strong>Telenet Systems GmbH\r\nAnton Maria Schyrle-Strasse 7\r\nA-6600 Reutte in Tirol\r\n\r\n<strong>Datenschutzerkl\u00e4rung:<\/strong>\u00a0 <a href=\"https:\/\/www.a1.digital\/ueber-a1-digital\/datenschutz-a1-digital\/\">Datenschutzerkl\u00e4rung<\/a><\/p><h2>Server Log Files<\/h2><span><p>Zum Zweck der \u00dcberwachung der technischen Funktion und zur Erh\u00f6hung der Betriebssicherheit unseres Webhosts werden Verbindungsdaten verarbeitet. Die Dauer der Verarbeitung ist auf 30 Tage beschr\u00e4nkt.<\/p><p>Die Rechtsgrundlage f\u00fcr die Datenverarbeitung ist die unbedingte technische Notwendigkeit eines Server Log Files als grundlegende Datenbasis zur Fehleranalyse und f\u00fcr Sicherheitsma\u00dfnahmen im Rahmen des durch Ihren Aufruf ausdr\u00fccklich gew\u00fcnschten Dienstes &#8220;Website&#8221; gem\u00e4\u00df \u00a7 165 Abs. 3 TKG 2021.<\/p><\/span><h2>Contact Form<\/h2><p><p>Auf unserer Website besteht die M\u00f6glichkeit, durch ein Kontaktformular direkt mit uns in Kontakt zu treten. Nach Absenden des Kontaktformulars erfolgt eine Verarbeitung der von Ihnen eingegebenen personenbezogenen Daten durch den Verantwortlichen zum Zweck der Bearbeitung Ihrer Anfrage auf Grundlage der von Ihnen durch das Absenden des Formulars erteilten Einwilligung gem. Art. 6 Abs. 1 lit. a DSGVO bis auf Widerruf.<br \/>Es besteht keine gesetzliche oder vertragliche Verpflichtung zur Bereitstellung der personenbezogenen Daten. Die Nichtbereitstellung hat lediglich zur Folge, dass Sie Ihr Anliegen nicht \u00fcbermitteln und wir dieses nicht bearbeiten k\u00f6nnen.<\/p><\/p><h2>Web Fonts<\/h2><h3>Adobe Fonts<\/h3><p><p>Wir verarbeiten mit unserem Auftragsverarbeiter <a target=\"_blank\" href=\"\/\/fonts.adobe.com\/\">Adobe Fonts<\/a>, Adobe Systems Software Ireland Limited, Citywest Business Campus, Dublin 24, Irland, Verbindungsdaten und Browserdaten zum Zweck der Bereitstellung der vom Webbrowser zur Anzeige der Website ben\u00f6tigten Schriftarten. Diese Daten werden nur f\u00fcr die zur Auswahl und \u00dcbermittlung der Schriftarten ben\u00f6tigte Dauer verarbeitet.<\/p><p>Die Rechtsgrundlage f\u00fcr die Datenverarbeitung ist die unbedingte technische Notwendigkeit zur Bereitstellung und Auslieferung des von Ihnen durch Ihren Aufruf ausdr\u00fccklich gew\u00fcnschten Dienstes &#8220;Website&#8221; gem\u00e4\u00df \u00a7 165 Abs. 3 TKG 2021.<\/p><p>Soweit durch Adobe Fonts eine weitergehende eigenst\u00e4ndige Verarbeitung der Daten erfolgt, ist Adobe Fonts daf\u00fcr alleinige Verantwortliche. Details finden Sie in der <a target=\"_blank\" href=\"https:\/\/www.adobe.com\/de\/privacy.html\">Datenschutzerkl\u00e4rung<\/a> von Adobe Fonts.<\/p><\/p><h2>Right to object<\/h2><p><p>Sofern die Verarbeitung Ihrer personenbezogenen Daten auf Grundlage des berechtigten Interesses erfolgt, haben Sie das Recht gegen diese Verarbeitung zu widersprechen.<\/p><p>Sofern keine zwingenden schutzw\u00fcrdigen Gr\u00fcnde f\u00fcr die Verarbeitung unsererseits vorliegen, wird die Verarbeitung Ihrer Daten auf Basis dieser Rechtsgrundlage eingestellt.<\/p><p>Zudem haben Sie das Recht, der Verarbeitung Ihrer personenbezogenen Daten zum Zweck der Direktwerbung zu widersprechen. Im Fall des Widerspruchs werden Ihre personenbezogenen Daten nicht mehr zum Zweck der Direktwerbung verarbeitet.<\/p><p>Die Rechtm\u00e4\u00dfigkeit der bis zum Widerspruch verarbeiteten Daten wird durch den Widerspruch nicht ber\u00fchrt.<\/p><\/p><h2>Withdrawal<\/h2><p><p>Sie haben das Recht eine bereits erteilte Einwilligung jederzeit zu widerrufen, indem Sie die <a target=\"_blank\" class=\"lwb-ppsp\" href=\"#\" title=\"Datenschutzeinstellungen\">Datenschutzeinstellungen<\/a> \u00e4ndern.<\/p><p>Im Fall der Einwilligung in den Erhalt elektronischer Werbung kann der Widerruf Ihrer Einwilligung durch Klick auf den Abmeldelink erfolgen. In diesem Fall wird eine Verarbeitung, sofern keine andere Rechtsgrundlage besteht, eingestellt.<\/p><p>Die Rechtm\u00e4\u00dfigkeit der bis zum Widerruf verarbeiteten Daten wird durch den Widerruf nicht ber\u00fchrt.<\/p><\/p><h2>Right to data subject<\/h2><p><p>Sie haben zudem das Recht auf Auskunft, Berichtigung, L\u00f6schung und Einschr\u00e4nkung der Verarbeitung der personenbezogenen Daten.<\/p><p>Soweit die Rechtsgrundlage der Verarbeitung Ihrer personenbezogenen Daten in Ihrer Einwilligung oder in einem mit Ihnen abgeschlossenen Vertrag besteht, haben Sie \u00fcberdies das Recht auf Daten\u00fcbertragbarkeit. <\/p><p>Weiters haben Sie das Recht auf Beschwerde bei der Aufsichtsbeh\u00f6rde. N\u00e4here Informationen zu den Aufsichtsbeh\u00f6rden in der Europ\u00e4ischen Union finden Sie <a target=\"_blank\" href=\"https:\/\/ec.europa.eu\/justice\/article-29\/structure\/data-protection-authorities\/index_en.htm\" title=\"Datenschutzbeh\u00f6rden\">hier<\/a>.<\/p><\/p>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"neve_meta_sidebar":"full-width","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"class_list":["post-7","page","type-page","status-publish","hentry"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"nl","enabled_languages":["de","nl","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"nl":{"title":true,"content":false,"excerpt":false},"en":{"title":true,"content":false,"excerpt":false}}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/campingehrwald.at\/nl\/wp-json\/wp\/v2\/pages\/7","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campingehrwald.at\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/campingehrwald.at\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/campingehrwald.at\/nl\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/campingehrwald.at\/nl\/wp-json\/wp\/v2\/comments?post=7"}],"version-history":[{"count":7,"href":"https:\/\/campingehrwald.at\/nl\/wp-json\/wp\/v2\/pages\/7\/revisions"}],"predecessor-version":[{"id":309,"href":"https:\/\/campingehrwald.at\/nl\/wp-json\/wp\/v2\/pages\/7\/revisions\/309"}],"wp:attachment":[{"href":"https:\/\/campingehrwald.at\/nl\/wp-json\/wp\/v2\/media?parent=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}